{"id":4709,"date":"2025-04-22T10:35:00","date_gmt":"2025-04-22T10:35:00","guid":{"rendered":"https:\/\/fondoaccion.org\/fi-wi-riif\/?post_type=news&#038;p=4709"},"modified":"2026-01-07T12:16:33","modified_gmt":"2026-01-07T12:16:33","slug":"avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia","status":"publish","type":"news","link":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/","title":{"rendered":"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-1024x684.jpg\" alt=\"\" class=\"wp-image-4713\" srcset=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-1024x684.jpg 1024w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-300x200.jpg 300w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-768x513.jpg 768w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-1536x1026.jpg 1536w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-2048x1368.jpg 2048w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1-18x12.jpg 18w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h4 class=\"wp-block-heading\" id=\"h-gracias-a-la-firma-de-este-acuerdo-avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-and-miss-graci-trabajaran-juntas-en-el-traslado-aereo-de-materiales-reciclables-como-carton-y-plastico-desde-la-isla-hacia-bogota-para-su-correcto-tratamiento-y-circularidad-la-corporacion-miss-raxi-and-miss-graci-trabaja-desde-2019-en-estrategias-de-sensibilizacion-con-la-comunidad-sobre-manejo-de-residuos-en-escuelas-iglesias-comercio-y-hogares-buscando-introducir-la-cultura-del-reciclaje-que-no-existia-en-las-islas-adicionalmente-se-encarga-de-embalar-transportar-y-entregar-a-un-gestor-autorizado-el-material-recolectado-para-su-transformacion-y-aprovechamiento-con-esta-alianza-avianca-reafirma-su-compromiso-con-la-conservacion-y-la-proteccion-de-la-reserva-de-biosfera-seaflower-reconocida-por-la-unesco-en-el-2000-esta-iniciativa-se-suma-a-las-alianzas-entre-avianca-y-ecoaventura-por-medio-de-la-cual-se-transportaron-mas-de-7-000-kg-de-materiales-reciclables-como-vidrio-carton-y-plastico-en-2024-y-mas-de-20-000-kg-desde-el-inicio-del-convenio-en-2022-apoyando-la-proteccion-de-las-islas-galapagos-y-el-trabajo-con-fundacion-habitat-sur-y-deprisa-en-la-amazonia-colombiana-con-el-transporte-de-4-toneladas-de-plasticos-de-un-solo-uso-desde-septiembre-de-2024\">Gracias a la firma de este acuerdo, Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi and Miss Graci trabajar\u00e1n juntas en el traslado a\u00e9reo de materiales reciclables como cart\u00f3n y pl\u00e1stico desde la isla hacia Bogot\u00e1, para su correcto tratamiento y circularidad.<br><br>La Corporaci\u00f3n Miss Raxi and Miss Graci, trabaja desde 2019 en estrategias de sensibilizaci\u00f3n con la comunidad sobre manejo de residuos en escuelas, iglesias, comercio y hogares, buscando introducir la cultura del reciclaje, que no exist\u00eda en las islas. Adicionalmente, se encarga de embalar, transportar y entregar a un gestor autorizado el material recolectado para su transformaci\u00f3n y aprovechamiento.<br><br>Con esta alianza, Avianca reafirma su compromiso con la conservaci\u00f3n y la protecci\u00f3n de la Reserva de Bi\u00f3sfera Seaflower, reconocida por la UNESCO en el 2000.<br><br>Esta iniciativa se suma a las alianzas entre Avianca y Ecoaventura, por medio de la cual se transportaron m\u00e1s de 7.000 kg de materiales reciclables como vidrio, cart\u00f3n y pl\u00e1stico en 2024 y m\u00e1s de 20.000 kg desde el inicio del convenio en 2022 apoyando la protecci\u00f3n de las Islas Gal\u00e1pagos y el trabajo con Fundaci\u00f3n H\u00e1bitat Sur y Deprisa en la Amazon\u00eda colombiana, con el transporte de 4 toneladas de pl\u00e1sticos de un solo uso desde septiembre de 2024.<\/h4>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Bogot\u00e1, 22 de abril de 2024 \u2013&nbsp;<\/strong>En el marco del d\u00eda mundial de la Tierra, Avianca anuncia la firma de un acuerdo con la Corporaci\u00f3n Miss Raxi and Miss Graci para trasladar mensualmente hasta 3 toneladas de cart\u00f3n y pl\u00e1stico desde San Andr\u00e9s y Providencia hacia Bogot\u00e1, para garantizar su tratamiento y reutilizaci\u00f3n. A este acuerdo se suman tambi\u00e9n Deprisa y Fondo Acci\u00f3n que con sus capacidades operativas y conocimiento de las islas aportar\u00e1n a la correcta ejecuci\u00f3n de este acuerdo en beneficio de las islas y su comunidad raizal.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acuerdo se da gracias a que, desde 2024, Avianca apoya el proyecto Fi Wii Riif (\u201cNuestro arrecife\u201d en lengua creole), liderado por Fondo Acci\u00f3n, que tiene como objetivo la protecci\u00f3n de la Reserva de Biosfera Seaflower, la cual es un \u00e1rea de excepcional importancia para el Caribe por su biodiversidad y cultura. Los residuos que sean retirados de las islas llegar\u00e1n a Bogot\u00e1 donde Ekored los recibir\u00e1 para darles el tratamiento y reutilizaci\u00f3n adecuada y as\u00ed lograr que la Corporaci\u00f3n Miss Raxi y Miss Graci pueda fortalecer sus capacidades, generar empleo y cuidar los ecosistemas del archipi\u00e9lago.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Este acuerdo se suma a los acuerdos que ya tiene Avianca con EcoAventura en las Islas Gal\u00e1pagos en Ecuador y con H\u00e1bitat Sur en Leticia en la Amazon\u00eda colombiana, de donde se han retirado en los \u00faltimos a\u00f1os m\u00e1s de 20 toneladas y 7 toneladas de desechos para su aprovechamiento, respectivamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aminta Robinson, directora de la Corporaci\u00f3n Miss Raxi and Miss Graci, una ONG local, destaca que su trabajo contribuye al cuidado de la reserva de bi\u00f3sfera Seaflower,<em>&nbsp;\u201cme duele saber que residuos aprovechables terminan en el relleno sanitario de la isla. Empec\u00e9 recogiendo y separando residuos aprovechables en mi casa y en mi entorno cercano; hoy ya logro recuperar una tonelada al mes. S\u00e9 que sola no hago el cambio, por eso, tener el apoyo de aliados como Avianca, Deprisa y Fondo Acci\u00f3n son el impulso que necesito para seguir adelante y fortalecer mi organizaci\u00f3n y el modelo de negocio.\u201d<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cDurante a\u00f1os, hemos puesto la capacidad de nuestros aviones para retirar residuos aprovechables de destinos clave para la biodiversidad del continente y que son destinos tur\u00edsticos muy valiosos. Empezamos con las Islas Gal\u00e1pagos en 2022; luego avanzamos con Leticia en 2024; y ahora lleg\u00f3 el momento de San Andr\u00e9s. Esto es solo posible gracias al trabajo admirable de organizaciones como la Corporaci\u00f3n Miss Raxi and Miss Graci y Fondo Acci\u00f3n que cuidan su entorno y conocen bien su valor y su magia. Nos honra trabajar con ellos,\u201d&nbsp;<\/em>afirm\u00f3 Felipe Andr\u00e9s G\u00f3mez Vivas, vicepresidente de Asuntos P\u00fablicos y Sostenibilidad de Avianca.&nbsp;<em>&nbsp;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><em>\u201cDesde el proyecto \u201cFi wi RIif\u201d apoyamos iniciativas que tienen beneficios ambientales al contribuir a la protecci\u00f3n de los ecosistemas, sociales al promover el bienestar humano y econ\u00f3micos al generar empleo y crecimiento de empresas y emprendimientos locales. De esto se trata el desarrollo sostenible que se impulsa en la reserva de bi\u00f3sfera Seaflower\u201d,<\/em>&nbsp;afirma Natalia Arango, directora ejecutiva de Fondo Acci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 ha implementado Avianca en cuanto a econom\u00eda circular?<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante el 2024, la aerol\u00ednea trabaj\u00f3 con diferentes organizaciones para el tratamiento de residuos aprovechando el 49% de residuos no peligrosos generados en sus principales estaciones de operaci\u00f3n. De este modo, se realizaron donaciones de material reciclable. beneficiando a recicladores de oficio en Colombia y a pacientes del \u00e1rea infantil de la Fundaci\u00f3n Hermano Miguel en Ecuador.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De igual forma, Avianca, en alianza con OPAIN y Waste2Worth, particip\u00f3 en el \u201cPacto por la Circularidad\u201d, una iniciativa que impulsa la econom\u00eda circular en el Aeropuerto El Dorado. Esta estrategia busca optimizar el uso de recursos, reducir la generaci\u00f3n de residuos y promover pr\u00e1cticas sostenibles en la gesti\u00f3n de envases y empaques. A trav\u00e9s de esta alianza, Avianca reafirma su compromiso con la sostenibilidad y la gesti\u00f3n responsable de materiales<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, desde 2022, la alianza entre Avianca y Ecoaventura ha permitido el transporte desde Gal\u00e1pagos hacia Quito de 20.101kg de residuos generados por actividades tur\u00edsticas. Este modelo tambi\u00e9n se replic\u00f3 en Leticia, Amazonas, en donde se han logrado transportar desde el inicio del convenio en septiembre de 2024, cerca de 4 toneladas de pl\u00e1sticos de un solo uso para ser transformados en textiles.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"684\" height=\"1024\" data-id=\"4710\" src=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-684x1024.jpg\" alt=\"\" class=\"wp-image-4710\" srcset=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-684x1024.jpg 684w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-200x300.jpg 200w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-768x1150.jpg 768w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-1026x1536.jpg 1026w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-1368x2048.jpg 1368w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1-8x12.jpg 8w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09518-scaled-1.jpg 1710w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"684\" height=\"1024\" data-id=\"4711\" src=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-684x1024.jpg\" alt=\"\" class=\"wp-image-4711\" srcset=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-684x1024.jpg 684w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-200x300.jpg 200w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-768x1150.jpg 768w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-1026x1536.jpg 1026w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-1368x2048.jpg 1368w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1-8x12.jpg 8w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00466-scaled-1.jpg 1710w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"684\" height=\"1024\" data-id=\"4712\" src=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-684x1024.jpg\" alt=\"\" class=\"wp-image-4712\" srcset=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-684x1024.jpg 684w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-200x300.jpg 200w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-768x1150.jpg 768w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-1026x1536.jpg 1026w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-1368x2048.jpg 1368w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1-8x12.jpg 8w, https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC00417-scaled-1.jpg 1710w\" sizes=\"(max-width: 684px) 100vw, 684px\" \/><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Refill for life<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para reafirmar su compromiso, Avianca en colaboraci\u00f3n con el Aeropuerto El Dorado en Bogot\u00e1, llev\u00f3 a cabo una activaci\u00f3n con los viajeros, a trav\u00e9s de la entrega de m\u00e1s de 100 termos en los puntos de hidrataci\u00f3n del aeropuerto. Esto, con el fin de desincentivar el uso de botellas pl\u00e1sticas e impulsar la cultura del \u201crefill\u201d.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adicionalmente, y teniendo en cuenta que en los puntos de hidrataci\u00f3n del Aeropuerto el Dorado se realizan cerca de 8.000 recargas diarias, Avianca don\u00f3 30 millas por cada una de ellas, alcanzando un total de 240.000 millas. Estas ser\u00e1n destinadas para transportar a profesionales de nuestros aliados ambientales como Agenda del Mar, Saving the Amazon y Fundaci\u00f3n Ruta Animal, quienes hacen parte del Banco de Millas de Lifemiles.<\/p>\n","protected":false},"featured_media":4713,"template":"","categoria-noticias":[],"class_list":["post-4709","news","type-news","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v24.5 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia - Fi Wi Riff<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia\" \/>\n<meta property=\"og:description\" content=\"Gracias a la firma de este acuerdo, Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi and Miss Graci trabajar\u00e1n juntas en el traslado a\u00e9reo de materiales reciclables como cart\u00f3n y pl\u00e1stico desde la isla hacia Bogot\u00e1, para su correcto tratamiento y circularidad. La Corporaci\u00f3n Miss Raxi and Miss Graci, trabaja desde 2019 en estrategias [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/\" \/>\n<meta property=\"og:site_name\" content=\"Fi Wi Riff\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T12:16:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1710\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/\",\"url\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/\",\"name\":\"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia - Fi Wi Riff\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DSC09532-scaled-1.jpg\",\"datePublished\":\"2025-04-22T10:35:00+00:00\",\"dateModified\":\"2026-01-07T12:16:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/#breadcrumb\"},\"inLanguage\":\"es-CO\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CO\",\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DSC09532-scaled-1.jpg\",\"contentUrl\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/wp-content\\\/uploads\\\/2025\\\/07\\\/DSC09532-scaled-1.jpg\",\"width\":2560,\"height\":1710},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/news\\\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/#website\",\"url\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/\",\"name\":\"Fi Wi Riff\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fondoaccion.org\\\/fi-wi-riif\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-CO\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia - Fi Wi Riff","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/","og_locale":"es_ES","og_type":"article","og_title":"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia","og_description":"Gracias a la firma de este acuerdo, Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi and Miss Graci trabajar\u00e1n juntas en el traslado a\u00e9reo de materiales reciclables como cart\u00f3n y pl\u00e1stico desde la isla hacia Bogot\u00e1, para su correcto tratamiento y circularidad. La Corporaci\u00f3n Miss Raxi and Miss Graci, trabaja desde 2019 en estrategias [&hellip;]","og_url":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/","og_site_name":"Fi Wi Riff","article_modified_time":"2026-01-07T12:16:33+00:00","og_image":[{"width":2560,"height":1710,"url":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/","url":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/","name":"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia - Fi Wi Riff","isPartOf":{"@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/#website"},"primaryImageOfPage":{"@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/#primaryimage"},"image":{"@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/#primaryimage"},"thumbnailUrl":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1.jpg","datePublished":"2025-04-22T10:35:00+00:00","dateModified":"2026-01-07T12:16:33+00:00","breadcrumb":{"@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/#breadcrumb"},"inLanguage":"es-CO","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/"]}]},{"@type":"ImageObject","inLanguage":"es-CO","@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/#primaryimage","url":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1.jpg","contentUrl":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-content\/uploads\/2025\/07\/DSC09532-scaled-1.jpg","width":2560,"height":1710},{"@type":"BreadcrumbList","@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/news\/avianca-deprisa-fondo-accion-y-la-corporacion-miss-raxi-y-miss-raci-firmaron-convenio-para-trasladar-hasta-3-toneladas-mensuales-de-materiales-reciclables-desde-la-isla-de-providencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/fondoaccion.org\/fi-wi-riif\/"},{"@type":"ListItem","position":2,"name":"Avianca, Deprisa, Fondo Acci\u00f3n y la Corporaci\u00f3n Miss Raxi y Miss Graci firmaron convenio para trasladar hasta 3 toneladas mensuales de materiales reciclables desde la isla de Providencia"}]},{"@type":"WebSite","@id":"https:\/\/fondoaccion.org\/fi-wi-riif\/#website","url":"https:\/\/fondoaccion.org\/fi-wi-riif\/","name":"Fi Wi Riff","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fondoaccion.org\/fi-wi-riif\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-CO"}]}},"_links":{"self":[{"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/news\/4709","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/news"}],"about":[{"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/types\/news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/media\/4713"}],"wp:attachment":[{"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/media?parent=4709"}],"wp:term":[{"taxonomy":"categoria-noticias","embeddable":true,"href":"https:\/\/fondoaccion.org\/fi-wi-riif\/wp-json\/wp\/v2\/categoria-noticias?post=4709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}